{"id":3205,"date":"2026-07-14T21:36:13","date_gmt":"2026-07-15T00:36:13","guid":{"rendered":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/?p=3205"},"modified":"2026-07-14T21:36:15","modified_gmt":"2026-07-15T00:36:15","slug":"si-prometo","status":"publish","type":"post","link":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/si-prometo\/","title":{"rendered":"\u00a1\u00a1SI PROMETO!!"},"content":{"rendered":"\n<p>El s\u00e1bado 20 de junio, alrededor de m\u00e1s 200 alumnos de escuelas primarias del Partido de La Costa realizaron la tradicional promesa de lealtad a la Bandera Nacional en un acto que reuni\u00f3 a familias, instituciones y autoridades locales.\u00a0<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><img decoding=\"async\" loading=\"lazy\" width=\"509\" height=\"510\" src=\"blob:https:\/\/isfdyt89-bue.infd.edu.ar\/9a11ec67-1b5f-4163-a362-570a6cf121ad\"><\/strong><\/p>\n\n\n\n<p>La Lucila del Mar volvi\u00f3 a convertirse en el escenario de una emotiva celebraci\u00f3n por el D\u00eda de la Bandera. El acto oficial se llev\u00f3 a cabo el <strong>s\u00e1bado 20 de junio de 2026<\/strong> en la Plaza Manuel Belgrano, ubicada entre las calles Rebagliati y Entre R\u00edos, donde vecinos, familias e instituciones de distintos puntos del Partido de La Costa se reunieron para conmemorar una de las fechas patrias m\u00e1s significativas del calendario nacional.<\/p>\n\n\n\n<p>El momento central de la jornada fue la tradicional promesa de lealtad a la Bandera Nacional, realizada por alrededor de m\u00e1s 200 alumnos y alumnas de 4\u00ba grado de las escuelas primarias N\u00ba 8 de Mar de Aj\u00f3 Norte, N\u00ba 11 de La Lucila del Mar, N\u00ba 14 de Aguas Verdes y N\u00ba 15 de San Bernardo. Bajo un cielo despejado y un radiante sol, los estudiantes vivieron uno de los momentos m\u00e1s importantes de su vida escolar, acompa\u00f1ados por veteranos de la Guerra de Malvinas, los grupos Scouts, Bomberos Voluntarios, autoridades educativas y sus familias.<\/p>\n\n\n\n<p>La ceremonia fue encabezada por el Intendente <strong>Juan de Jes\u00fas<\/strong>, junto a concejales, funcionarios municipales, soberanas de las fiestas nacionales y una gran cantidad de vecinos y vecinas que participaron del encuentro.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" width=\"533\" height=\"709.2189781021898\" src=\"blob:https:\/\/isfdyt89-bue.infd.edu.ar\/6b0665fc-22cc-4715-a565-cc60d1d7af92\"><\/p>\n\n\n\n<p>Antes de la promesa, el intendente dirigi\u00f3 unas palabras a los estudiantes, destacando el profundo significado de los colores patrios. En ese sentido, expres\u00f3 que el celeste y blanco de la bandera representan <strong>\u00absu lugar de pertenencia\u00bb<\/strong> y agreg\u00f3: <strong>\u00abEsta es una promesa de amor a la patria, a nuestros valores, tradiciones, creencias y anhelos\u00bb<\/strong>, invitando a los presentes a valorar el compromiso que implica honrar la bandera argentina.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" width=\"382.5581395348837\" height=\"555.0445026178011\" src=\"blob:https:\/\/isfdyt89-bue.infd.edu.ar\/97779799-cd2e-4747-8d01-4b650416a3a9\"><\/p>\n\n\n\n<p>Finalizado el acto protocolar, la jornada continu\u00f3 con un clima de encuentro y celebraci\u00f3n comunitaria. Los vecinos recorrieron la feria artesanal y los puestos organizados por las distintas escuelas primarias, donde se ofrecieron empanadas, tortas fritas, panchos y otras propuestas gastron\u00f3micas. Adem\u00e1s, la Asociaci\u00f3n de Fomento de La Lucila del Mar comparti\u00f3 chocolate caliente con los vecinos de la zona, un gesto que acompa\u00f1\u00f3 el c\u00e1lido ambiente vivido durante toda la jornada.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" width=\"488\" height=\"650.4815087730957\" src=\"blob:https:\/\/isfdyt89-bue.infd.edu.ar\/721499cd-af94-49dd-a321-4df9217b0c62\"><\/p>\n\n\n\n<p>Nota informativa realizada por Malena Gianelli, estudiante de Comunicaci\u00f3n Social para el Desarrollo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 20 de junio, alrededor de m\u00e1s 200 alumnos de escuelas primarias del Partido de La Costa realizaron la tradicional promesa de lealtad a la Bandera Nacional en un acto que reuni\u00f3 a familias, instituciones y autoridades locales.\u00a0 La Lucila del Mar volvi\u00f3 a convertirse en el escenario de una emotiva celebraci\u00f3n por el &#8230; <a title=\"\u00a1\u00a1SI PROMETO!!\" class=\"read-more\" href=\"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/si-prometo\/\" aria-label=\"More on \u00a1\u00a1SI PROMETO!!\">[+]<\/a><\/p>\n","protected":false},"author":2608,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3205"}],"collection":[{"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/2608"}],"replies":[{"embeddable":true,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3205"}],"version-history":[{"count":1,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3205\/revisions"}],"predecessor-version":[{"id":3206,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3205\/revisions\/3206"}],"wp:attachment":[{"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isfdyt89-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}